{"id":8522,"count":2,"description":"","link":"https:\/\/disterri.com\/es\/categoria-producto\/refrescos\/lata\/nestea-es\/","name":"Nestea","slug":"nestea-es","taxonomy":"product_cat","parent":8513,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nestea Archives - Disterri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/disterri.com\/es\/categoria-producto\/refrescos\/lata\/nestea-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nestea Archives - Disterri\" \/>\n<meta property=\"og:url\" content=\"https:\/\/disterri.com\/es\/categoria-producto\/refrescos\/lata\/nestea-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Disterri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/disterri.com\\\/es\\\/categoria-producto\\\/refrescos\\\/lata\\\/nestea-es\\\/\",\"url\":\"https:\\\/\\\/disterri.com\\\/es\\\/categoria-producto\\\/refrescos\\\/lata\\\/nestea-es\\\/\",\"name\":\"Nestea Archives - Disterri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/disterri.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/disterri.com\\\/es\\\/categoria-producto\\\/refrescos\\\/lata\\\/nestea-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/disterri.com\\\/es\\\/categoria-producto\\\/refrescos\\\/lata\\\/nestea-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/disterri.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Refrescos\",\"item\":\"https:\\\/\\\/disterri.com\\\/es\\\/categoria-producto\\\/refrescos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lata\",\"item\":\"https:\\\/\\\/disterri.com\\\/es\\\/categoria-producto\\\/refrescos\\\/lata\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Nestea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/disterri.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/disterri.com\\\/es\\\/\",\"name\":\"Disterri\",\"description\":\"Distribuci\u00f3n de bebidas y alimentaci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/disterri.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/disterri.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/disterri.com\\\/es\\\/#organization\",\"name\":\"Disterri\",\"url\":\"https:\\\/\\\/disterri.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/disterri.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/disterri.com\\\/wp-content\\\/uploads\\\/cropped-logo-disterri.png\",\"contentUrl\":\"https:\\\/\\\/disterri.com\\\/wp-content\\\/uploads\\\/cropped-logo-disterri.png\",\"width\":216,\"height\":45,\"caption\":\"Disterri\"},\"image\":{\"@id\":\"https:\\\/\\\/disterri.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nestea Archives - Disterri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/disterri.com\/es\/categoria-producto\/refrescos\/lata\/nestea-es\/","og_locale":"es_ES","og_type":"article","og_title":"Nestea Archives - Disterri","og_url":"https:\/\/disterri.com\/es\/categoria-producto\/refrescos\/lata\/nestea-es\/","og_site_name":"Disterri","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/disterri.com\/es\/categoria-producto\/refrescos\/lata\/nestea-es\/","url":"https:\/\/disterri.com\/es\/categoria-producto\/refrescos\/lata\/nestea-es\/","name":"Nestea Archives - Disterri","isPartOf":{"@id":"https:\/\/disterri.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/disterri.com\/es\/categoria-producto\/refrescos\/lata\/nestea-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/disterri.com\/es\/categoria-producto\/refrescos\/lata\/nestea-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/disterri.com\/es\/"},{"@type":"ListItem","position":2,"name":"Refrescos","item":"https:\/\/disterri.com\/es\/categoria-producto\/refrescos\/"},{"@type":"ListItem","position":3,"name":"Lata","item":"https:\/\/disterri.com\/es\/categoria-producto\/refrescos\/lata\/"},{"@type":"ListItem","position":4,"name":"Nestea"}]},{"@type":"WebSite","@id":"https:\/\/disterri.com\/es\/#website","url":"https:\/\/disterri.com\/es\/","name":"Disterri","description":"Distribuci\u00f3n de bebidas y alimentaci\u00f3n","publisher":{"@id":"https:\/\/disterri.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/disterri.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/disterri.com\/es\/#organization","name":"Disterri","url":"https:\/\/disterri.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/disterri.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/disterri.com\/wp-content\/uploads\/cropped-logo-disterri.png","contentUrl":"https:\/\/disterri.com\/wp-content\/uploads\/cropped-logo-disterri.png","width":216,"height":45,"caption":"Disterri"},"image":{"@id":"https:\/\/disterri.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/disterri.com\/es\/wp-json\/wp\/v2\/product_cat\/8522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/disterri.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/disterri.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/disterri.com\/es\/wp-json\/wp\/v2\/product_cat\/8513"}],"wp:post_type":[{"href":"https:\/\/disterri.com\/es\/wp-json\/wp\/v2\/product?product_cat=8522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}